{"id":41450,"date":"2022-08-26T19:15:32","date_gmt":"2022-08-26T13:45:32","guid":{"rendered":"https:\/\/presskitaquat.com\/?p=41450"},"modified":"2022-08-26T19:15:32","modified_gmt":"2022-08-26T13:45:32","slug":"allahabad-highcourt-news","status":"publish","type":"post","link":"https:\/\/presskitaquat.com\/english\/allahabad-highcourt-news\/","title":{"rendered":"\u0907\u0932\u093e\u0939\u092c\u093e\u0926 \u0939\u093e\u0908 \u0915\u094b\u0930\u094d\u091f \u092e\u0947\u0902 \u092e\u0941\u0958\u0926\u092e\u0947 \u0926\u093e\u0916\u093f\u0932 \u0939\u094b\u0928\u0947 \u092e\u0947\u0902 \u0926\u0947\u0930\u0940 \u0915\u093e \u092e\u093e\u092e\u0932\u093e"},"content":{"rendered":"<p>\u0932\u0916\u0928\u090a(\u0935\u093f\u0936\u093e\u0932 \u0935\u0930\u094d\u092e\u093e)- \u091c\u094d\u091e\u093e\u0924 \u0939\u094b \u0915\u0940 \u0968\u096a \u0905\u0917\u0938\u094d\u0924 \u0915\u094b \u0907\u0932\u093e\u0939\u092c\u093e\u0926 \u0939\u093e\u0908 \u0915\u094b\u0930\u094d\u091f \u092c\u093e\u0930 \u090f\u0938\u094b\u0938\u093f\u090f\u0936\u0928 \u0915\u0947 \u0905\u0927\u094d\u092f\u0915\u094d\u0937 \u0930\u093e\u0927\u093e\u0915\u093e\u0902\u0924 \u0913\u091d\u093e \u0915\u0940 \u0905\u0917\u0941\u0906\u0908 \u092e\u0947\u0902 \u090f\u0915 \u092c\u0948\u0920\u0915 \u0939\u0941\u0908 \u091c\u093f\u0938\u092e\u0947 \u0907\u0928 \u092e\u0941\u0926\u094d\u0926\u094b\u0902 \u092a\u0930 \u091a\u0930\u094d\u091a\u093e \u0915\u0947 \u092c\u093e\u0926 \u092c\u095d\u093e\u0924\u0947 \u0939\u0941\u090f \u0935\u093f\u0930\u094b\u0927 \u092a\u094d\u0930\u0926\u0930\u094d\u0936\u0928 \u0915\u0930\u0928\u0947 \u0915\u093e \u0928\u093f\u0930\u094d\u0923\u092f \u0932\u093f\u092f\u093e \u0917\u092f\u093e\u0964 \u091c\u093f\u0928 \u092e\u0941\u0926\u094d\u0926\u094b\u0902 \u092a\u0930 \u092c\u093e\u0930 \u090f\u0938\u094b\u0938\u093f\u090f\u0936\u0928 \u0915\u0947 \u0938\u0926\u0938\u094d\u092f\u094b\u0902 \u0928\u0947 \u092c\u0948\u0920\u0915 \u0915\u0940 \u0909\u0928\u092e\u0947 \u092a\u094d\u0930\u092e\u0941\u0916 \u0930\u0942\u092a \u0938\u0947 \u0905\u0927\u093f\u0935\u0915\u094d\u0924\u093e \u092e\u0941\u0915\u0926\u092e\u094b\u0902 \u0915\u0947 \u0926\u093e\u0916\u093f\u0932 \u0915\u0930\u0928\u0947 \u0926\u0947\u0930\u0940, \u0905\u0928\u0932\u093f\u0938\u094d\u091f\u0947\u0921, \u0938\u0941\u092a\u094d\u092a\u094d\u0932\u093f\u092e\u0947\u0902\u091f\u094d\u0930\u0940 \u0935 \u0928\u090f \u092e\u0941\u0915\u0926\u092e\u094b\u0902 \u0915\u0947 \u0938\u0942\u091a\u0940\u092c\u0926\u094d\u0927 \u0928 \u0939\u094b\u0928\u0947 \u0938\u092e\u0947\u0924 \u0915\u0908 \u0936\u093f\u0915\u093e\u092f\u0924\u0947\u0902 \u0936\u093e\u092e\u093f\u0932 \u0939\u0948\u0902\u0964 \u0907\u0938\u0940 \u0915\u094d\u0930\u092e \u092e\u0947\u0902 \u0939\u093e\u0908 \u0915\u094b\u0930\u094d\u091f \u0915\u0947 \u0935\u0915\u0940\u0932\u094b\u0902 \u0928\u0947 \u0968\u096b \u0905\u0917\u0938\u094d\u0924 \u0915\u094b \u092d\u0940 \u0928\u094d\u092f\u093e\u092f\u0932\u092f \u0915\u0940 \u0915\u093e\u0930\u094d\u092f\u0935\u093e\u0939\u0940 \u092e\u0947\u0902 \u0938\u092e\u094d\u092e\u093f\u0932\u093f\u0924 \u0928 \u0939\u094b\u0928\u0947 \u0915\u093e \u0928\u093f\u0930\u094d\u0923\u092f \u0932\u093f\u092f\u093e \u0939\u0948\u0964 \u092c\u093e\u0930 \u090f\u0938\u094b\u0938\u093f\u090f\u0936\u0928 \u0915\u0947 \u092a\u0926\u093e\u0927\u093f\u0915\u093e\u0930\u093f\u092f\u094b\u0902 \u0915\u0947 \u092e\u0941\u0924\u093e\u092c\u093f\u0915 \u0928\u094d\u092f\u093e\u092f\u092e\u0942\u0930\u094d\u0924\u093f\u092f\u094b\u0902 \u0915\u0940 \u0938\u0902\u0916\u094d\u092f\u093e \u0906\u0935\u0936\u094d\u092f\u0915\u0924\u093e \u0938\u0947 \u0915\u092e \u092f\u0925\u093e \u0967\u096c\u0966 \u0915\u0940 \u0924\u0941\u0932\u0928\u093e \u092e\u0947\u0902 \u0932\u0917\u092d\u0917 \u0967\u0966\u0966 \u0939\u094b\u0928\u0947 \u0915\u0947 \u0915\u093e\u0930\u0928 \u0938\u092e\u0938\u094d\u092f\u093e \u0915\u093e\u092e \u0939\u094b\u0928\u0947 \u0915\u093e \u0928\u093e\u092e \u0928\u0939\u0940\u0902 \u0932\u0947 \u0930\u0939\u0940 \u0939\u0948\u0902\u0964 \u0907\u0938\u0932\u093f\u090f \u0905\u0927\u093f\u0935\u0915\u094d\u0924\u093e\u0913\u0902 \u0915\u0940 \u092e\u093e\u0902\u0917 \u0939\u0948 \u0915\u0940 \u092f\u0925\u093e\u0936\u0940\u0918\u094d\u0930 \u0930\u093f\u0915\u094d\u0924 \u092a\u0926\u094b\u0902 \u092a\u0930 \u0928\u093f\u092f\u0941\u0915\u094d\u0924\u093f\u092f\u093e\u0902 \u0915\u0940 \u091c\u093e\u090f\u0901\u0964<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0932\u0916\u0928\u090a(\u0935\u093f\u0936\u093e\u0932 \u0935\u0930\u094d\u092e\u093e)- \u091c\u094d\u091e\u093e\u0924 \u0939\u094b \u0915\u0940 \u0968\u096a \u0905\u0917\u0938\u094d\u0924 \u0915\u094b \u0907\u0932\u093e\u0939\u092c\u093e\u0926 \u0939\u093e\u0908 \u0915\u094b\u0930\u094d\u091f \u092c\u093e\u0930 \u090f\u0938\u094b\u0938\u093f\u090f\u0936\u0928 \u0915\u0947 \u0905\u0927\u094d\u092f\u0915\u094d\u0937 \u0930\u093e\u0927\u093e\u0915\u093e\u0902\u0924 \u0913\u091d\u093e \u0915\u0940 \u0905\u0917\u0941\u0906\u0908 \u092e\u0947\u0902 \u090f\u0915 \u092c\u0948\u0920\u0915 \u0939\u0941\u0908 \u091c\u093f\u0938\u092e\u0947 \u0907\u0928 \u092e\u0941\u0926\u094d\u0926\u094b\u0902 \u092a\u0930 \u091a\u0930\u094d\u091a\u093e \u0915\u0947 \u092c\u093e\u0926 \u092c\u095d\u093e\u0924\u0947 \u0939\u0941\u090f \u0935\u093f\u0930\u094b\u0927 \u092a\u094d\u0930\u0926\u0930\u094d\u0936\u0928 \u0915\u0930\u0928\u0947 \u0915\u093e \u0928\u093f\u0930\u094d\u0923\u092f \u0932\u093f\u092f\u093e \u0917\u092f\u093e\u0964 \u091c\u093f\u0928 \u092e\u0941\u0926\u094d\u0926\u094b\u0902 \u092a\u0930 \u092c\u093e\u0930 \u090f\u0938\u094b\u0938\u093f\u090f\u0936\u0928 \u0915\u0947 \u0938\u0926\u0938\u094d\u092f\u094b\u0902 \u0928\u0947 \u092c\u0948\u0920\u0915 \u0915\u0940 \u0909\u0928\u092e\u0947 \u092a\u094d\u0930\u092e\u0941\u0916 \u0930\u0942\u092a \u0938\u0947 \u0905\u0927\u093f\u0935\u0915\u094d\u0924\u093e \u092e\u0941\u0915\u0926\u092e\u094b\u0902 [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":41451,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"footnotes":""},"categories":[20],"tags":[],"class_list":["post-41450","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-india"],"_links":{"self":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/posts\/41450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/comments?post=41450"}],"version-history":[{"count":1,"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/posts\/41450\/revisions"}],"predecessor-version":[{"id":41452,"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/posts\/41450\/revisions\/41452"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/media\/41451"}],"wp:attachment":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/media?parent=41450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/categories?post=41450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/tags?post=41450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}