{"id":11791,"count":1,"description":"","link":"https:\/\/presskitaquat.com\/english\/tag\/corona-proximity\/","name":"corona proximity","slug":"corona-proximity","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/tags\/11791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/posts?tags=11791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}