{"id":2228,"count":1,"description":"","link":"https:\/\/presskitaquat.com\/english\/tag\/%e0%a8%b0%e0%a8%a3%e0%a8%a6%e0%a9%80%e0%a8%aa-%e0%a8%b8%e0%a8%bf%e0%a9%b0%e0%a8%98-%e0%a8%86%e0%a8%b9%e0%a8%b2%e0%a9%82%e0%a8%b5%e0%a8%be%e0%a8%b2%e0%a9%80%e0%a8%86\/","name":"\u0a30\u0a23\u0a26\u0a40\u0a2a \u0a38\u0a3f\u0a70\u0a18 \u0a06\u0a39\u0a32\u0a42\u0a35\u0a3e\u0a32\u0a40\u0a06","slug":"%e0%a8%b0%e0%a8%a3%e0%a8%a6%e0%a9%80%e0%a8%aa-%e0%a8%b8%e0%a8%bf%e0%a9%b0%e0%a8%98-%e0%a8%86%e0%a8%b9%e0%a8%b2%e0%a9%82%e0%a8%b5%e0%a8%be%e0%a8%b2%e0%a9%80%e0%a8%86","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/tags\/2228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/posts?tags=2228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}