{"id":22526,"count":1,"description":"","link":"https:\/\/presskitaquat.com\/english\/tag\/next-exam-current-affairs\/","name":"next exam current affairs","slug":"next-exam-current-affairs","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/tags\/22526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/posts?tags=22526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}