{"id":23113,"count":1,"description":"","link":"https:\/\/presskitaquat.com\/english\/tag\/children-injured-in-bus-crash\/","name":"children injured in bus crash","slug":"children-injured-in-bus-crash","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/tags\/23113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/posts?tags=23113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}