{"id":25689,"count":1,"description":"","link":"https:\/\/presskitaquat.com\/english\/tag\/raghav-chadha-video\/","name":"raghav chadha video","slug":"raghav-chadha-video","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/tags\/25689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/posts?tags=25689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}