{"id":28728,"count":1,"description":"","link":"https:\/\/presskitaquat.com\/english\/tag\/why-didnt-harry-potter-die-in-the-forbidden-forest\/","name":"why didn't harry potter die in the forbidden forest","slug":"why-didnt-harry-potter-die-in-the-forbidden-forest","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/tags\/28728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/posts?tags=28728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}