{"id":2889,"count":1,"description":"","link":"https:\/\/presskitaquat.com\/english\/tag\/us-sends-2-aircraft-carriers-to-south-china-sea-during-pla-drills\/","name":"US sends 2 aircraft carriers to South China Sea during PLA drills","slug":"us-sends-2-aircraft-carriers-to-south-china-sea-during-pla-drills","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/tags\/2889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/posts?tags=2889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}