{"id":40161,"count":1,"description":"","link":"https:\/\/presskitaquat.com\/english\/tag\/sh-aman-mohi\/","name":"Sh. Aman Mohi","slug":"sh-aman-mohi","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/tags\/40161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/presskitaquat.com\/english\/wp-json\/wp\/v2\/posts?tags=40161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}